{"id":9424,"date":"2020-04-21T13:00:48","date_gmt":"2020-04-21T13:00:48","guid":{"rendered":"https:\/\/www.logomaker.com\/blog\/2020\/04\/21\/como-fazer-logo-desenhado-a-mao\/"},"modified":"2024-03-07T16:17:11","modified_gmt":"2024-03-07T16:17:11","slug":"como-fazer-logo-desenhado-a-mao","status":"publish","type":"post","link":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/","title":{"rendered":"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O processo de cria\u00e7\u00e3o de um logo pode ser tedioso e demorado.&nbsp;Entretanto,&nbsp;no fim de tudo, ele \u00e9 um s\u00edmbolo para o seu neg\u00f3cio,&nbsp;podcast,&nbsp;evento sem fins lucrativos, etc.&nbsp;que vai resistir ao teste do tempo!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma das melhores t\u00e9cnicas para&nbsp;construir um logo marcante&nbsp;\u00e9 come\u00e7ar com um logotipo feito \u00e0 m\u00e3o e expandir a ideia contida nele, parte por parte.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O&nbsp;logo&nbsp;que voc\u00ea faz como rascunho ir\u00e1 servir como um ponto inicial&nbsp;para o resto dos seus detalhes.&nbsp;Mas pode levar algumas tentativas para que ele fique da forma correta pretendida&nbsp;por voc\u00ea.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui est\u00e3o v\u00e1rias dicas de como criar um&nbsp;logo criado \u00e0 m\u00e3o que voc\u00ea pode utilizar pelo resto do processo.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Considere o Tom Que o Seu&nbsp;Logo&nbsp;Precisa&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cada&nbsp;logo&nbsp;tem um tom&nbsp;que ele define quando um cliente coloca os olhos nele.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, o logo da&nbsp;UPS&nbsp;possui um tom muito profissional e sensato&nbsp;que \u00e9 exatamente o que voc\u00ea est\u00e1 procurando nos servi\u00e7os de frete que eles fornecem.&nbsp;A&nbsp;Target&nbsp;possui um tom balanceado em seu logo,&nbsp;assim como o balan\u00e7o dos itens que a sua loja fornece&#8230;&nbsp;voc\u00ea deve ter pegado a ideia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fim de alcan\u00e7ar um tom apropriado,&nbsp;voc\u00ea precisa sempre estar se fazendo algumas perguntas fundamentais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para quem o logo \u00e9 destinado a atrair?&nbsp;Que&nbsp;vibe&nbsp;voc\u00ea est\u00e1 tentando definir?&nbsp;Existem&nbsp;s\u00edmbolos universais que podem suportar o&nbsp;<a href=\"https:\/\/www.forbes.com\/sites\/kateharrison\/2018\/08\/14\/what-message-does-your-logo-convey\/\" target=\"_blank\" aria-label=\"(Opens a new window)\" rel=\"noreferrer noopener\">significado do seu&nbsp;logo<\/a>&nbsp;(tais como uma cruz m\u00e9dica para um hospital ou uma camiseta, bola para um logo de equipe de futebol)?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenha em mente,&nbsp;o&nbsp;logo&nbsp;que voc\u00ea desenha n\u00e3o \u00e9 apenas o&nbsp;<em>\u00fanico<\/em>&nbsp;caminho para comunicar o tom para a sua marca.&nbsp;Coisas como&nbsp;<a href=\"https:\/\/www.oberlo.com\/blog\/color-psychology-color-meanings\" target=\"_blank\" aria-label=\"(Opens a new window)\" rel=\"noreferrer noopener\">as cores que voc\u00ea utiliza<\/a>&nbsp;podem&nbsp;de forma subliminar definir o tom para voc\u00ea,&nbsp;ent\u00e3o n\u00e3o se estresse muito com essa parte do processo de design de logo.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2.&nbsp;Hora de Fazer o&nbsp;Brainstorm&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea possui algumas ideias do tom para o seu logo que voc\u00ea quer criar \u00e0 m\u00e3o,&nbsp;\u00e9 hora de descobrir como capturar isso de forma apropriada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea provavelmente possui algumas formas diferentes de pensar como ter uma ideia para um&nbsp;<a href=\"https:\/\/www.logomaker.com\/logo-design\/\" target=\"_blank\" aria-label=\"(Opens a new window)\" rel=\"noreferrer noopener\">design de logo de sucesso<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por que manter essas ideias presas na sua cabe\u00e7a?&nbsp;Comece a fazer o&nbsp;brainstorming&nbsp;ao pegar um peda\u00e7o de papel e desenhar alguns logos diferentes.&nbsp;Esses rascunhos podem ser t\u00e3o detalhados ou t\u00e3o b\u00e1sicos quanto poss\u00edvel,&nbsp;o que quer que voc\u00ea sinta que capture a sua ideia da melhor forma.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O que voc\u00ea ir\u00e1 perceber \u00e9 que,&nbsp;ap\u00f3s alinhar todas as suas ideias&nbsp;pr\u00f3ximas umas das outras,&nbsp;existem alguns designs que ir\u00e3o se destacar do resto.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Esses<\/em>&nbsp;s\u00e3o aqueles que voc\u00ea ir\u00e1 querer explorar mais a fundo!&nbsp;Se voc\u00ea quer procurar algumas outras opini\u00f5es&nbsp;(al\u00e9m da sua pr\u00f3pria), ent\u00e3o leve a p\u00e1gina de&nbsp;brainstorm&nbsp;aos seus colegas de trabalho ou parentes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sinta-se livre para&nbsp;pedir votos a eles,&nbsp;veja que logos conseguem a maioria dos votos,&nbsp;e ent\u00e3o utilize eles como o trampolim para o seu logo desenhado \u00e0 m\u00e3o.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3.&nbsp;Fa\u00e7a Experimentos com o&nbsp;Design&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00f3 porque voc\u00ea possui um design ou dois que se destacaram do resto, n\u00e3o significa que voc\u00ea terminou de refinar os detalhes desses logos.&nbsp;Existem v\u00e1rias formas de fazer com que esse logo fique ainda melhor do que antes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, experimente estilos de fonte com o mesmo logo ou layout que voc\u00ea quer utilizar para o rascunho final.&nbsp;Veja quais s\u00e3o as que melhor se encaixam com o estilo que voc\u00ea escolheu.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Experimente incluir&nbsp;algumas formas diferentes no logo que possam complement\u00e1-lo sem fazer com que fique complicado demais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, digamos que voc\u00ea esteja criando um logotipo para uma empresa que faz telhados.&nbsp;Ao utilizar um tri\u00e2ngulo acima do nome da empresa, todo mundo que v\u00ea saber\u00e1 que a sua empresa tem a ver com telhados.&nbsp;Melhor ainda,&nbsp;ele mant\u00e9m o design simplista que voc\u00ea est\u00e1 procurando.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outro recurso bacana para colocar em seu logo \u00e9 o uso do espa\u00e7o negativo.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4.&nbsp;Fa\u00e7a um Rascu<strong>nho&nbsp;Final<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea sabe todos os recursos que voc\u00ea quer incorporar no seu design, \u00e9 hora de fazer um rascunho final para o seu logo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pegue todos os rascunhos que voc\u00ea criou at\u00e9 agora e transforme-os&nbsp;em uma vers\u00e3o abrangente do&nbsp;brainstorming&nbsp;que voc\u00ea fez.&nbsp;Voc\u00ea pode&nbsp;encontrar alguns recursos no \u00faltimo momento.&nbsp;N\u00e3o h\u00e1 nada errado com isso!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certifique-se que o rascunho final seja uma vers\u00e3o muito maior de cada logo que voc\u00ea criou at\u00e9 esse ponto.&nbsp;Quanto maior ele for, mais detalhes voc\u00ea pode incluir no rascunho mais tarde.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certifique-se de fazer todos os tamanhos e propor\u00e7\u00f5es apropriados.&nbsp;Voc\u00ea quer que o logo seja t\u00e3o f\u00e1cil de ser percebido aos olhos quanto poss\u00edvel antes de adicionar cor a ele.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Digitalize o Rascunho&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Obviamente,&nbsp;esse logo desenhado \u00e0 m\u00e3o n\u00e3o far\u00e1 muito bem \u00e0 sua empresa sem que ele seja convertido para um<a href=\"https:\/\/www.logomaker.com\/what-you-get\/\" target=\"_blank\" aria-label=\"(Opens a new window)\" rel=\"noreferrer noopener\">&nbsp;<\/a><a href=\"https:\/\/www.logomaker.com\/what-you-get\/\" target=\"_blank\" aria-label=\"(Opens a new window)\" rel=\"noreferrer noopener\">formato digitalizado<\/a>&nbsp;tal como um arquivo PDF ou JPEG.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existem v\u00e1rios programas excelentes a\u00ed fora que permitem a voc\u00ea escanear&nbsp;o seu logo desenhado \u00e0 m\u00e3o&nbsp;e refinar seus detalhes em um programa de ilustra\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certifique-se de considerar todas as op\u00e7\u00f5es \u00e0 sua disposi\u00e7\u00e3o e escolha o programa que voc\u00ea acha que melhor se encaixa com as suas necessidades.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Um Logo Desenhado \u00e0 M\u00e3o&nbsp;N\u00e3o \u00e9 a Sua \u00danica Op\u00e7\u00e3o&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Para aqueles de voc\u00eas por a\u00ed que pensavam que um logo desenhado \u00e0 m\u00e3o era a sua \u00fanica op\u00e7\u00e3o para criar o logotipo dos seus sonhos, voc\u00ea estava errado!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para quaisquer perguntas que voc\u00ea possa ter,&nbsp;sinta-se livre para entrar em contato atrav\u00e9s da nossa p\u00e1gina de&nbsp;<a href=\"https:\/\/www.logomaker.com\/contact-us\/\" target=\"_blank\" aria-label=\"(Opens a new window)\" rel=\"noreferrer noopener\">suporte de atendimento ao cliente<\/a>&nbsp;e ficaremos felizes em ajud\u00e1-lo com quaisquer d\u00favidas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O processo de cria\u00e7\u00e3o de um logo pode ser tedioso e demorado.&nbsp;Entretanto,&nbsp;no fim de tudo, ele \u00e9 um s\u00edmbolo para o seu neg\u00f3cio,&nbsp;podcast,&nbsp;evento sem fins lucrativos, etc.&nbsp;que vai resistir ao teste do tempo!&nbsp; Uma das melhores t\u00e9cnicas para&nbsp;construir um logo marcante&nbsp;\u00e9 come\u00e7ar com um logotipo feito \u00e0 m\u00e3o e expandir a ideia contida nele, parte [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":9056,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,54],"tags":[],"class_list":["post-9424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-ptbr"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito | LogoMaker<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito | LogoMaker\" \/>\n<meta property=\"og:description\" content=\"O processo de cria\u00e7\u00e3o de um logo pode ser tedioso e demorado.&nbsp;Entretanto,&nbsp;no fim de tudo, ele \u00e9 um s\u00edmbolo para o seu neg\u00f3cio,&nbsp;podcast,&nbsp;evento sem fins lucrativos, etc.&nbsp;que vai resistir ao teste do tempo!&nbsp; Uma das melhores t\u00e9cnicas para&nbsp;construir um logo marcante&nbsp;\u00e9 come\u00e7ar com um logotipo feito \u00e0 m\u00e3o e expandir a ideia contida nele, parte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/\" \/>\n<meta property=\"og:site_name\" content=\"LogoMaker\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-21T13:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T16:17:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.logomaker.com\/wp-content\/uploads\/2020\/02\/hand-drawn-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stacy Cyr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stacy Cyr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/\"},\"author\":{\"name\":\"Stacy Cyr\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#\\\/schema\\\/person\\\/8c5b9c699c4a9b068ea0299a7e17f840\"},\"headline\":\"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito\",\"datePublished\":\"2020-04-21T13:00:48+00:00\",\"dateModified\":\"2024-03-07T16:17:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/\"},\"wordCount\":1120,\"publisher\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.logomaker.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/hand-drawn-logo.jpg\",\"articleSection\":[\"Destaque\",\"ptbr\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/\",\"url\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/\",\"name\":\"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito | LogoMaker\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.logomaker.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/hand-drawn-logo.jpg\",\"datePublished\":\"2020-04-21T13:00:48+00:00\",\"dateModified\":\"2024-03-07T16:17:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.logomaker.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/hand-drawn-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.logomaker.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/hand-drawn-logo.jpg\",\"width\":2000,\"height\":1331,\"caption\":\"hand-drawn logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/como-fazer-logo-desenhado-a-mao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destaque\",\"item\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/category\\\/destaque\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/\",\"name\":\"LogoMaker Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#organization\"},\"alternateName\":\"LogoMaker\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#organization\",\"name\":\"LogoMaker\",\"alternateName\":\"LMK\",\"url\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"LogoMaker\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/#\\\/schema\\\/person\\\/8c5b9c699c4a9b068ea0299a7e17f840\",\"name\":\"Stacy Cyr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a83067d2351d51716906af96cd73e72cc2802c5e9c563839c584aab0cc3a14f?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a83067d2351d51716906af96cd73e72cc2802c5e9c563839c584aab0cc3a14f?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a83067d2351d51716906af96cd73e72cc2802c5e9c563839c584aab0cc3a14f?s=96&r=g\",\"caption\":\"Stacy Cyr\"},\"url\":\"https:\\\/\\\/www.logomaker.com\\\/blog\\\/pt-br\\\/author\\\/stacy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito | LogoMaker","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/","og_locale":"pt_BR","og_type":"article","og_title":"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito | LogoMaker","og_description":"O processo de cria\u00e7\u00e3o de um logo pode ser tedioso e demorado.&nbsp;Entretanto,&nbsp;no fim de tudo, ele \u00e9 um s\u00edmbolo para o seu neg\u00f3cio,&nbsp;podcast,&nbsp;evento sem fins lucrativos, etc.&nbsp;que vai resistir ao teste do tempo!&nbsp; Uma das melhores t\u00e9cnicas para&nbsp;construir um logo marcante&nbsp;\u00e9 come\u00e7ar com um logotipo feito \u00e0 m\u00e3o e expandir a ideia contida nele, parte [&hellip;]","og_url":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/","og_site_name":"LogoMaker","article_published_time":"2020-04-21T13:00:48+00:00","article_modified_time":"2024-03-07T16:17:11+00:00","og_image":[{"width":2000,"height":1331,"url":"https:\/\/www.logomaker.com\/wp-content\/uploads\/2020\/02\/hand-drawn-logo.jpg","type":"image\/jpeg"}],"author":"Stacy Cyr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Stacy Cyr","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/#article","isPartOf":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/"},"author":{"name":"Stacy Cyr","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#\/schema\/person\/8c5b9c699c4a9b068ea0299a7e17f840"},"headline":"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito","datePublished":"2020-04-21T13:00:48+00:00","dateModified":"2024-03-07T16:17:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/"},"wordCount":1120,"publisher":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#organization"},"image":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.logomaker.com\/wp-content\/uploads\/2020\/02\/hand-drawn-logo.jpg","articleSection":["Destaque","ptbr"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/","url":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/","name":"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito | LogoMaker","isPartOf":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/#primaryimage"},"image":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.logomaker.com\/wp-content\/uploads\/2020\/02\/hand-drawn-logo.jpg","datePublished":"2020-04-21T13:00:48+00:00","dateModified":"2024-03-07T16:17:11+00:00","breadcrumb":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/#primaryimage","url":"https:\/\/www.logomaker.com\/wp-content\/uploads\/2020\/02\/hand-drawn-logo.jpg","contentUrl":"https:\/\/www.logomaker.com\/wp-content\/uploads\/2020\/02\/hand-drawn-logo.jpg","width":2000,"height":1331,"caption":"hand-drawn logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/como-fazer-logo-desenhado-a-mao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.logomaker.com\/blog\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Destaque","item":"https:\/\/www.logomaker.com\/blog\/pt-br\/category\/destaque\/"},{"@type":"ListItem","position":3,"name":"Como Fazer o Logo Desenhado \u00e0 M\u00e3o Perfeito"}]},{"@type":"WebSite","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#website","url":"https:\/\/www.logomaker.com\/blog\/pt-br\/","name":"LogoMaker Blog","description":"","publisher":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#organization"},"alternateName":"LogoMaker","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.logomaker.com\/blog\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#organization","name":"LogoMaker","alternateName":"LMK","url":"https:\/\/www.logomaker.com\/blog\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"LogoMaker"},"image":{"@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.logomaker.com\/blog\/pt-br\/#\/schema\/person\/8c5b9c699c4a9b068ea0299a7e17f840","name":"Stacy Cyr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3a83067d2351d51716906af96cd73e72cc2802c5e9c563839c584aab0cc3a14f?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3a83067d2351d51716906af96cd73e72cc2802c5e9c563839c584aab0cc3a14f?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a83067d2351d51716906af96cd73e72cc2802c5e9c563839c584aab0cc3a14f?s=96&r=g","caption":"Stacy Cyr"},"url":"https:\/\/www.logomaker.com\/blog\/pt-br\/author\/stacy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts\/9424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/comments?post=9424"}],"version-history":[{"count":1,"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts\/9424\/revisions"}],"predecessor-version":[{"id":9987,"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts\/9424\/revisions\/9987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/media\/9056"}],"wp:attachment":[{"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/media?parent=9424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/categories?post=9424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.logomaker.com\/blog\/pt-br\/wp-json\/wp\/v2\/tags?post=9424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}